{"id":6757,"date":"2025-04-08T18:32:59","date_gmt":"2025-04-08T22:32:59","guid":{"rendered":""},"modified":"2026-04-26T20:45:55","modified_gmt":"2026-04-27T00:45:55","slug":"handmade-brick","status":"publish","type":"wl_products","link":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/","title":{"rendered":"Handmade Brick"},"featured_media":4733,"template":"","wl_products_cats":[104,115],"wl_products_brands":[53],"class_list":["post-6757","wl_products","type-wl_products","status-publish","has-post-thumbnail","hentry","wl_products_cats-adhered-stones","wl_products_cats-decorative-stones"],"acf":{"wl_product_desc":"Inspired by the warmth of old brick structures on the American East Coast. Depending on your color and design choices, this brick can be warm and charming or industrial and modern.","wl_products_colors":false,"wl_products_colors_v2":[{"wl_products_colors_img":8889,"wl_products_colors_name":"Canvas"},{"wl_products_colors_img":8890,"wl_products_colors_name":"Carbon"},{"wl_products_colors_img":8888,"wl_products_colors_name":"Moroccan Sand"},{"wl_products_colors_img":8887,"wl_products_colors_name":"Titanium"}],"wl_products_brands":53,"wl_products_collections":false,"wl_products_cats":[104,115],"wl_product_loop_Main":false,"wl_product_loop_main_pos":"Par d\u00e9faut","wl_product_img_ls1":8892,"wl_product_img_ls1_pos":"Par d\u00e9faut","wl_product_img_ls2":8891,"wl_product_img_ls2_pos":"Par d\u00e9faut","wl_product_file_ft":6799,"wl_product_img_hero":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Handmade Brick - Blocs Mirabel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Handmade Brick - Blocs Mirabel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/\" \/>\n<meta property=\"og:site_name\" content=\"Blocs Mirabel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T00:45:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2025\/04\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1278\" \/>\n\t<meta property=\"og:image:height\" content=\"1346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/\",\"url\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/\",\"name\":\"Handmade Brick - Blocs Mirabel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blocsmirabel.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg\",\"datePublished\":\"2025-04-08T22:32:59+00:00\",\"dateModified\":\"2026-04-27T00:45:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blocsmirabel.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg\",\"contentUrl\":\"https:\\\/\\\/blocsmirabel.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg\",\"width\":1278,\"height\":1346},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/adhered-stones\\\/handmade-brick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adhered Stones\",\"item\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/collection\\\/adhered-stones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Handmade Brick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/\",\"name\":\"Bloc Mirabel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/#organization\",\"name\":\"Bloc Mirabel\",\"url\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blocsmirabel.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/bloc-mirabel-logo.png\",\"contentUrl\":\"https:\\\/\\\/blocsmirabel.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/bloc-mirabel-logo.png\",\"width\":362,\"height\":130,\"caption\":\"Bloc Mirabel\"},\"image\":{\"@id\":\"https:\\\/\\\/blocsmirabel.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Handmade Brick - Blocs Mirabel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/","og_locale":"en_US","og_type":"article","og_title":"Handmade Brick - Blocs Mirabel","og_url":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/","og_site_name":"Blocs Mirabel","article_modified_time":"2026-04-27T00:45:55+00:00","og_image":[{"width":1278,"height":1346,"url":"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2025\/04\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/","url":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/","name":"Handmade Brick - Blocs Mirabel","isPartOf":{"@id":"https:\/\/blocsmirabel.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/#primaryimage"},"image":{"@id":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/#primaryimage"},"thumbnailUrl":"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2025\/04\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg","datePublished":"2025-04-08T22:32:59+00:00","dateModified":"2026-04-27T00:45:55+00:00","breadcrumb":{"@id":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/#primaryimage","url":"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2025\/04\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg","contentUrl":"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2025\/04\/CulturedStone_Pierres_Deco_Handmade-Brick-Titunium-TM.jpg","width":1278,"height":1346},{"@type":"BreadcrumbList","@id":"https:\/\/blocsmirabel.com\/en\/adhered-stones\/handmade-brick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blocsmirabel.com\/en\/"},{"@type":"ListItem","position":2,"name":"Adhered Stones","item":"https:\/\/blocsmirabel.com\/en\/collection\/adhered-stones\/"},{"@type":"ListItem","position":3,"name":"Handmade Brick"}]},{"@type":"WebSite","@id":"https:\/\/blocsmirabel.com\/en\/#website","url":"https:\/\/blocsmirabel.com\/en\/","name":"Bloc Mirabel","description":"","publisher":{"@id":"https:\/\/blocsmirabel.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blocsmirabel.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blocsmirabel.com\/en\/#organization","name":"Bloc Mirabel","url":"https:\/\/blocsmirabel.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blocsmirabel.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2020\/10\/bloc-mirabel-logo.png","contentUrl":"https:\/\/blocsmirabel.com\/wp-content\/uploads\/2020\/10\/bloc-mirabel-logo.png","width":362,"height":130,"caption":"Bloc Mirabel"},"image":{"@id":"https:\/\/blocsmirabel.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products\/6757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products"}],"about":[{"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/types\/wl_products"}],"version-history":[{"count":1,"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products\/6757\/revisions"}],"predecessor-version":[{"id":8893,"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products\/6757\/revisions\/8893"}],"acf:term":[{"embeddable":true,"taxonomy":"wl_products_cats","href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products_cats\/115"},{"embeddable":true,"taxonomy":"wl_products_cats","href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products_cats\/104"},{"embeddable":true,"taxonomy":"wl_products_brands","href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products_brands\/53"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/media\/4733"}],"wp:attachment":[{"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/media?parent=6757"}],"wp:term":[{"taxonomy":"wl_products_cats","embeddable":true,"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products_cats?post=6757"},{"taxonomy":"wl_products_brands","embeddable":true,"href":"https:\/\/blocsmirabel.com\/en\/wp-json\/wp\/v2\/wl_products_brands?post=6757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}